{"id":168102,"date":"2026-09-02T12:41:00","date_gmt":"2026-09-02T16:41:00","guid":{"rendered":"https:\/\/www.campogrande.ms.gov.br\/cgnoticias\/?post_type=sec-noticias&#038;p=168102"},"modified":"2026-09-02T12:07:50","modified_gmt":"2026-09-02T16:07:50","slug":"ciamp-rua-completa-um-ano-de-atuacao-em-campo-grande","status":"publish","type":"sec-noticias","link":"https:\/\/www.campogrande.ms.gov.br\/cgnoticias\/noticia\/ciamp-rua-completa-um-ano-de-atuacao-em-campo-grande\/","title":{"rendered":"CIAMP-Rua completa um ano de atua\u00e7\u00e3o em Campo Grande"},"content":{"rendered":"\n<p>O Comit\u00ea Intersetorial de Acompanhamento e Monitoramento da Pol\u00edtica para a Popula\u00e7\u00e3o em Situa\u00e7\u00e3o de Rua (CIAMP-Rua) completa um ano de atua\u00e7\u00e3o em Campo Grande com a participa\u00e7\u00e3o em iniciativas voltadas \u00e0 prote\u00e7\u00e3o social e \u00e0 garantia de direitos. Criado para acompanhar a pol\u00edtica municipal e articular diferentes setores, o comit\u00ea participou, no per\u00edodo, de a\u00e7\u00f5es como o Censo da popula\u00e7\u00e3o em situa\u00e7\u00e3o de rua, o Inverno Acolhedor e a ades\u00e3o da Capital ao Plano Nacional Ruas Vis\u00edveis.<\/p>\n\n\n\n<p>Institu\u00eddo pelo Decreto Municipal n\u00ba 16.256\/2025, o CIAMP-Rua re\u00fane representantes do poder p\u00fablico e da sociedade civil. Entre suas atribui\u00e7\u00f5es est\u00e3o o acompanhamento e o monitoramento da Pol\u00edtica Municipal para a Popula\u00e7\u00e3o em Situa\u00e7\u00e3o de Rua, a articula\u00e7\u00e3o entre institui\u00e7\u00f5es e a contribui\u00e7\u00e3o para ampliar o acesso dessa popula\u00e7\u00e3o \u00e0s pol\u00edticas p\u00fablicas.<\/p>\n\n\n\n<p>Ao longo do primeiro ano, o comit\u00ea tamb\u00e9m estruturou seu funcionamento, com defini\u00e7\u00e3o da diretoria, aprova\u00e7\u00e3o do Regimento Interno e delibera\u00e7\u00f5es relacionadas ao acompanhamento e \u00e0 pol\u00edtica municipal para a popula\u00e7\u00e3o em situa\u00e7\u00e3o de rua.<\/p>\n\n\n\n<p>Entre as iniciativas acompanhadas est\u00e1 o Censo da popula\u00e7\u00e3o em situa\u00e7\u00e3o de rua de Campo Grande, divulgado em agosto em alus\u00e3o ao Dia Nacional de Luta da Popula\u00e7\u00e3o em Situa\u00e7\u00e3o de Rua. O levantamento busca ampliar o conhecimento sobre o perfil e as demandas desse p\u00fablico e oferecer dados para subsidiar o planejamento das pol\u00edticas p\u00fablicas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"605\" src=\"https:\/\/cdn.campogrande.ms.gov.br\/portal\/prod\/uploads\/sites\/3\/2026\/09\/WhatsApp-Image-2026-08-31-at-14.23.19-2-1024x605.jpeg\" alt=\"\" class=\"wp-image-168104\" srcset=\"https:\/\/cdn.campogrande.ms.gov.br\/portal\/prod\/uploads\/sites\/3\/2026\/09\/WhatsApp-Image-2026-08-31-at-14.23.19-2-1024x605.jpeg 1024w, https:\/\/cdn.campogrande.ms.gov.br\/portal\/prod\/uploads\/sites\/3\/2026\/09\/WhatsApp-Image-2026-08-31-at-14.23.19-2-300x177.jpeg 300w, https:\/\/cdn.campogrande.ms.gov.br\/portal\/prod\/uploads\/sites\/3\/2026\/09\/WhatsApp-Image-2026-08-31-at-14.23.19-2-768x454.jpeg 768w, https:\/\/cdn.campogrande.ms.gov.br\/portal\/prod\/uploads\/sites\/3\/2026\/09\/WhatsApp-Image-2026-08-31-at-14.23.19-2-275x163.jpeg 275w, https:\/\/cdn.campogrande.ms.gov.br\/portal\/prod\/uploads\/sites\/3\/2026\/09\/WhatsApp-Image-2026-08-31-at-14.23.19-2.jpeg 1262w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>O CIAMP-Rua tamb\u00e9m acompanhou o Inverno Acolhedor, iniciativa desenvolvida pela Secretaria de Assist\u00eancia Social e Cidadania (SAS) desde o ano passado. Durante os per\u00edodos de frio intenso, o ponto de apoio organizado no Parque Ayrton Senna j\u00e1 contabiliza mais de 1,8 mil acolhimentos desde 2025.<\/p>\n\n\n\n<p>Outro marco do per\u00edodo foi a ades\u00e3o de Campo Grande ao Plano Nacional Ruas Vis\u00edveis, articulada pela Superintend\u00eancia de Pol\u00edtica de Direitos Humanos e formalizada pela Prefeitura no m\u00eas passado. A presidente do CIAMP-Rua, Priscila Justi, destaca a participa\u00e7\u00e3o do comit\u00ea nesse processo, que contou com recomenda\u00e7\u00e3o favor\u00e1vel \u00e0 ades\u00e3o do munic\u00edpio.<\/p>\n\n\n\n<p>A implementa\u00e7\u00e3o e a articula\u00e7\u00e3o das diretrizes nacionais em Campo Grande ser\u00e3o conduzidas pela Secretaria Municipal de Desenvolvimento Humano e Social (SDHU), em parceria com o CIAMP-Rua. A proposta envolve a atua\u00e7\u00e3o integrada de diferentes \u00e1reas, como sa\u00fade, habita\u00e7\u00e3o, trabalho, educa\u00e7\u00e3o e seguran\u00e7a alimentar.<\/p>\n\n\n\n<p>\u201cO conjunto dessas iniciativas demonstra o fortalecimento, ao longo do primeiro ano, de um espa\u00e7o permanente de di\u00e1logo, participa\u00e7\u00e3o e controle social. A atua\u00e7\u00e3o do CIAMP-Rua contribui para que a Pol\u00edtica Municipal para a Popula\u00e7\u00e3o em Situa\u00e7\u00e3o de Rua avance de forma intersetorial, com acompanhamento das a\u00e7\u00f5es do poder p\u00fablico e participa\u00e7\u00e3o da sociedade civil na constru\u00e7\u00e3o das respostas \u00e0s demandas dessa popula\u00e7\u00e3o\u201d, ressaltou a superintendente de Pol\u00edticas de Direitos Humanos da SAS e presidente do Comit\u00ea, Priscila Justi.<\/p>\n","protected":false},"author":310,"featured_media":168103,"template":"","meta":{"custom_icon_class":"","footnotes":""},"categories":[131],"tags":[],"class_list":["post-168102","sec-noticias","type-sec-noticias","status-publish","has-post-thumbnail","hentry","category-administracao"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.campogrande.ms.gov.br\/cgnoticias\/wp-json\/wp\/v2\/sec-noticias\/168102"}],"collection":[{"href":"https:\/\/www.campogrande.ms.gov.br\/cgnoticias\/wp-json\/wp\/v2\/sec-noticias"}],"about":[{"href":"https:\/\/www.campogrande.ms.gov.br\/cgnoticias\/wp-json\/wp\/v2\/types\/sec-noticias"}],"author":[{"embeddable":true,"href":"https:\/\/www.campogrande.ms.gov.br\/cgnoticias\/wp-json\/wp\/v2\/users\/310"}],"version-history":[{"count":2,"href":"https:\/\/www.campogrande.ms.gov.br\/cgnoticias\/wp-json\/wp\/v2\/sec-noticias\/168102\/revisions"}],"predecessor-version":[{"id":168106,"href":"https:\/\/www.campogrande.ms.gov.br\/cgnoticias\/wp-json\/wp\/v2\/sec-noticias\/168102\/revisions\/168106"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.campogrande.ms.gov.br\/cgnoticias\/wp-json\/wp\/v2\/media\/168103"}],"wp:attachment":[{"href":"https:\/\/www.campogrande.ms.gov.br\/cgnoticias\/wp-json\/wp\/v2\/media?parent=168102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.campogrande.ms.gov.br\/cgnoticias\/wp-json\/wp\/v2\/categories?post=168102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.campogrande.ms.gov.br\/cgnoticias\/wp-json\/wp\/v2\/tags?post=168102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}